{"id":7233,"date":"2021-11-09T16:08:28","date_gmt":"2021-11-09T13:08:28","guid":{"rendered":"https:\/\/nh-logistics.com\/certificacion\/"},"modified":"2021-11-09T16:08:34","modified_gmt":"2021-11-09T13:08:34","slug":"certificacion","status":"publish","type":"page","link":"https:\/\/nh-logistics.com\/es\/certificacion\/","title":{"rendered":"CERTIFICACI\u00d3N"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=\u00bbstretch_row\u00bb css=\u00bb.vc_custom_1625722693067{padding-top: 50px !important;padding-bottom: 35px !important;background-color: #f1f1f1 !important;}\u00bb][vc_column css=\u00bb.vc_custom_1625574278990{padding-top: 0px !important;padding-bottom: 0px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00bb][vc_custom_heading text=\u00bbCERTIFICACI\u00d3N\u00bb font_container=\u00bbtag:h1|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb css=\u00bb.vc_custom_1627455526048{padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][\/vc_column][\/vc_row][vc_row gap=\u00bb10&#8243;][vc_column width=\u00bb3\/4&#8243; css=\u00bb.vc_custom_1625484159638{padding-top: 0px !important;}\u00bb][vc_single_image image=\u00bb7235&#8243; img_size=\u00bbfull\u00bb][vc_column_text]Durante muchos a\u00f1os, NH Logistics ha apoyado a sus Clientes en el campo de la importaci\u00f3n a Rusia. Una parte importante del proceso de importaci\u00f3n son los certificados que exige la ley al importar al territorio de la Federaci\u00f3n de Rusia.<\/p>\n<p>Dichos certificados son una prueba documental de la conformidad de su producto con los est\u00e1ndares de calidad, que es seguro y se puede utilizar libremente en el mercado ruso. Actualmente, la mayor\u00eda de los productos que est\u00e1n presentes en los mercados internacionales y rusos deben tener una certificaci\u00f3n obligatoria. Si un fabricante o importador no obtiene un certificado para dicho producto de acuerdo con la ley rusa, se trata de una infracci\u00f3n administrativa. Si los productos no est\u00e1n sujetos a la certificaci\u00f3n obligatoria, para aumentar la competitividad, podr\u00eda optar por realizar una certificaci\u00f3n voluntaria.<\/p>\n<p>Entendemos muy bien lo complicado que es el proceso de certificaci\u00f3n para una empresa extranjera que trabaja en Rusia. Es por ello que NH Logistics realiza los m\u00e1ximos esfuerzos para conseguir la m\u00e1xima eficiencia y sencillez en nuestras comunicaciones.<\/p>\n<p>Al concluir el acuerdo de comercio exterior, debe incluir la obligaci\u00f3n del proveedor extranjero de proporcionar, si es necesario, certificado o declaraci\u00f3n.<br \/>\nLos certificados \/ declaraci\u00f3n se env\u00edan a la aduana junto con la declaraci\u00f3n de aduana de carga y estos documentos son necesarios para obtener un permiso para importar mercanc\u00edas a Rusia.<br \/>\nLa certificaci\u00f3n tambi\u00e9n brinda otras ventajas a los fabricantes e importadores.<\/p>\n<p>En primer lugar, la certificaci\u00f3n de productos puede ayudar a los fabricantes e importadores a vender sus productos de calidad, teniendo ventajas competitivas sobre sus competidores.<br \/>\nEn segundo lugar, la certificaci\u00f3n ofrece tranquilidad a los usuarios de dichos productos, sabiendo que compran un producto seguro y confiable.<\/p>\n<p>NH Logistics puede organizar el proceso de tal forma que recibas tus certificados en el menor tiempo posible. Durante el proceso de certificaci\u00f3n cooperamos con muchas organizaciones oficiales rusas y nuestros vol\u00famenes nos ayudan a ofrecer a nuestros clientes precios asequibles por este servicio.<\/p>\n<p>Nuestro personal est\u00e1 calificado para procesar solicitudes de certificaci\u00f3n y aprobaciones para muchos tipos de productos, incluidos <a href=\"https:\/\/nh-logistics.com\/other-services\/eurasian-customs-union-certificate\/\">GOST<\/a> (reglamentos t\u00e9cnicos), <a href=\"https:\/\/nh-logistics.com\/other-services\/hygienic-certificate-russia\/\">higiene<\/a> , <a href=\"https:\/\/nh-logistics.com\/other-services\/fire-safety-certificate-russia\/\">seguridad contra incendios<\/a> , <a href=\"https:\/\/nh-logistics.com\/other-services\/fss-fsb-notification\/\">notificaciones FSB \/ FSS<\/a> y <a href=\"https:\/\/nh-logistics.com\/other-services\/medical-registration-certificate\/\">certificado de registro m\u00e9dico<\/a> .<\/p>\n<p>Puede encontrar informaci\u00f3n \u00fatil en el sitio web: <a href=\"https:\/\/www.trade.gov\/knowledge-product\/russia-standards-trade\" target=\"_blank\" rel=\"noopener nofollow\">www.trade.gov<\/a>[\/vc_column_text][vc_column_text el_class=\u00bbboxCountrPages\u00bb css=\u00bb.vc_custom_1628580917054{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: #f4f4f4 !important;}\u00bb]<\/p>\n<h2>Algunas razones por las que deber\u00eda trabajar con nosotros:<\/h2>\n<ul>\n<li>Activo en Eurasia y la CEI desde 2001<\/li>\n<li>Hablamos su idioma, ruso, ingl\u00e9s, alem\u00e1n, holand\u00e9s<\/li>\n<li>Entidades propias en <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/servicios-ior-eor-rusia\/\">Rusia<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/ior-eor-bielorrusia\/\">Bielorrusia<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/ior-eor-services-ucrania\/\">Ucrania<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/ior-eor-azerbaiyan\/\">Azerbaiy\u00e1n<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/ior-eor-kazajstan\/\">Kazajst\u00e1n<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/servicios-ior-eor-uzbekistan\/\">Uzbekist\u00e1n<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/ior-eor-servicios-moldova\/\">Moldavia<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/ior-eor-armenia\/\">Armenia<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/ior-eor-georgia\/\">Georgia<\/a> , <a href=\"https:\/\/nh-logistics.com\/es\/ior-eor-ddp\/importador-de-registro-de-servicios\/servicios-ior-eor-serbia\/\">Serbia<\/a><\/li>\n<li>Nuestros especialistas comprenden muy bien los requisitos y los est\u00e1ndares internacionales de producci\u00f3n.<\/li>\n<li>Le ayudaremos a obtener todos los dem\u00e1s permisos \/ aprobaciones necesarios.<\/li>\n<li>Nuestro personal es flexible y orientado al cliente.<\/li>\n<li>NH Logistics te consultar\u00e1 y te ofrecer\u00e1 la mejor soluci\u00f3n seg\u00fan tus necesidades<\/li>\n<li>Le proporcionaremos toda la asistencia y el apoyo necesarios a trav\u00e9s de nuestras oficinas en Rusia y Eurasia.<\/li>\n<li>\u00a1Nuestro personal es amable y lo ayudar\u00e1 a resolver sus desaf\u00edos con mucho gusto!<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1625485002142{padding-top: 0px !important;}\u00bb][vc_raw_html css=\u00bb.vc_custom_1625485008464{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: #1f425d !important;}\u00bb]W2NvbnRhY3QtZm9ybS03IGlkPSIyOSJd[\/vc_raw_html][vc_column_text]\u2611 <strong>Activo en Rusia y la CEI desde 2001.<\/strong><br \/>\n\u2611 <strong>Entidades en 7 pa\u00edses de la CEI.<\/strong><br \/>\n\u2611 <strong>Fuente todo en uno.<\/strong><br \/>\n\u2611 <strong>Satisfacci\u00f3n del cliente garantizada.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00bbstretch_row\u00bb css=\u00bb.vc_custom_1627388559066{margin-bottom: 0px !important;background: #f5f5f5 url(https:\/\/nh-logistics.com\/wp-content\/uploads\/2021\/07\/cntrBackground.jpg?id=1039) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00bb][vc_column][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">Contamos con la confianza de empresas internacionales desde 2001<\/h3>\n<p style=\"text-align: center;\">Describa en detalle el servicio que desea solicitar. \u00a1Estamos aqu\u00ed para apoyarte!<\/p>\n<p style=\"text-align: center;\">Puede realizar una consulta a trav\u00e9s de <a href=\"mailto:info@nh-logistics.com\">info@nh-logistics.com<\/a> para recibir una consulta inicial.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=\u00bbstretch_row\u00bb css=\u00bb.vc_custom_1625722693067{padding-top: 50px !important;padding-bottom: 35px !important;background-color: #f1f1f1 !important;}\u00bb][vc_column css=\u00bb.vc_custom_1625574278990{padding-top: 0px !important;padding-bottom: 0px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00bb][vc_custom_heading text=\u00bbCERTIFICACI\u00d3N\u00bb font_container=\u00bbtag:h1|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb css=\u00bb.vc_custom_1627455526048{padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][\/vc_column][\/vc_row][vc_row gap=\u00bb10&#8243;][vc_column width=\u00bb3\/4&#8243; css=\u00bb.vc_custom_1625484159638{padding-top: 0px !important;}\u00bb][vc_single_image image=\u00bb7235&#8243; img_size=\u00bbfull\u00bb][vc_column_text]Durante muchos a\u00f1os, NH Logistics ha apoyado a sus Clientes en el campo de la importaci\u00f3n a Rusia. Una parte importante &#8230; <a title=\"CERTIFICACI\u00d3N\" class=\"read-more\" href=\"https:\/\/nh-logistics.com\/es\/certificacion\/\" aria-label=\"M\u00e1s en CERTIFICACI\u00d3N\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7233","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/nh-logistics.com\/es\/wp-json\/wp\/v2\/pages\/7233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nh-logistics.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nh-logistics.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nh-logistics.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nh-logistics.com\/es\/wp-json\/wp\/v2\/comments?post=7233"}],"version-history":[{"count":0,"href":"https:\/\/nh-logistics.com\/es\/wp-json\/wp\/v2\/pages\/7233\/revisions"}],"wp:attachment":[{"href":"https:\/\/nh-logistics.com\/es\/wp-json\/wp\/v2\/media?parent=7233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}